{"id":2309,"date":"2016-04-13T14:29:32","date_gmt":"2016-04-13T19:29:32","guid":{"rendered":"http:\/\/conurbados.com\/?p=2309"},"modified":"2016-04-13T14:29:32","modified_gmt":"2016-04-13T19:29:32","slug":"a-punto-de-cerrar-prepa-de-axochiapan-por-falta-de-recursos","status":"publish","type":"post","link":"https:\/\/conurbados.com\/portal\/a-punto-de-cerrar-prepa-de-axochiapan-por-falta-de-recursos\/","title":{"rendered":"A punto de cerrar prepa de Axochiapan por falta de recursos"},"content":{"rendered":"<figure id=\"attachment_2310\" aria-describedby=\"caption-attachment-2310\" style=\"width: 423px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2310\" data-permalink=\"https:\/\/conurbados.com\/portal\/a-punto-de-cerrar-prepa-de-axochiapan-por-falta-de-recursos\/fernando-mendoza\/\" data-orig-file=\"https:\/\/conurbados.com\/portal\/wp-content\/uploads\/2016\/04\/Fernando-Mendoza.jpg\" data-orig-size=\"423,635\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Fernando Mendoza\" data-image-description=\"&lt;p&gt;Fernando Mendoza&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Fernando Mendoza&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/conurbados.com\/portal\/wp-content\/uploads\/2016\/04\/Fernando-Mendoza-300x450.jpg\" data-large-file=\"https:\/\/conurbados.com\/portal\/wp-content\/uploads\/2016\/04\/Fernando-Mendoza.jpg\" class=\"size-full wp-image-2310\" src=\"http:\/\/conurbados.com\/portal\/wp-content\/uploads\/2016\/04\/Fernando-Mendoza.jpg\" alt=\"Fernando Mendoza\" width=\"423\" height=\"635\" srcset=\"https:\/\/conurbados.com\/portal\/wp-content\/uploads\/2016\/04\/Fernando-Mendoza.jpg 423w, https:\/\/conurbados.com\/portal\/wp-content\/uploads\/2016\/04\/Fernando-Mendoza-100x150.jpg 100w, https:\/\/conurbados.com\/portal\/wp-content\/uploads\/2016\/04\/Fernando-Mendoza-300x450.jpg 300w\" sizes=\"auto, (max-width: 423px) 85vw, 423px\" \/><figcaption id=\"caption-attachment-2310\" class=\"wp-caption-text\">Fernando Mendoza<\/figcaption><\/figure>\n<p>Por Silvia Lozano Venegas<\/p>\n<p>Cuernavaca, Morelos; 13 de abril de 2016. El coordinador estatal de preparatorias federales, Fernando Mendoza, revel\u00f3 que la preparatoria de Axochiapan est\u00e1 a punto de cerrar por\u00a0 falta de recursos, y que en la actualidad son los padres de familia quienes sostienen la instituci\u00f3n con sus aportaciones.<\/p>\n<p>En entrevista, Fernando Mendoza dijo que en Morelos s\u00f3lo cuentan con nueve preparatorias federales y la del municipio de Axochiapan est\u00e1 en riesgo de cerrar porque no reciben ning\u00fan subsidio federal ni estatal, m\u00e1s que la beca salario y los padres de familia tienen que pagar 300 pesos mensuales por cada estudiante.<\/p>\n<p>Detall\u00f3 que debido a esta situaci\u00f3n, los padres de familia han optado por inscribir a sus hijos a otros planteles donde no cobran y su matr\u00edcula ha disminuido considerablemente y s\u00f3lo quedan 120 estudiantes, a pesar de que su preparatoria tiene capacidad para m\u00e1s de 600 estudiantes.<\/p>\n<p>Fernando Mendoza coment\u00f3 que desde el gobierno de Vicente Fox, con la reforma Educativa omitieron dotar de recursos a las preparatorias federales y desde entonces han tenido que gestionar recursos y con la aportaci\u00f3n de los padres de familia han podido continuar.<\/p>\n<p>Pero que ya est\u00e1n en pl\u00e1ticas con el Gobierno Federal para que se les incluya en el presupuesto y no cierren m\u00e1s planteles, como ocurri\u00f3 hace cinco a\u00f1os en Mazatepec, que la preparatoria tuvo que cerrar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Silvia Lozano Venegas Cuernavaca, Morelos; 13 de abril de 2016. El coordinador estatal de preparatorias federales, Fernando Mendoza, revel\u00f3 que la preparatoria de Axochiapan est\u00e1 a punto de cerrar por\u00a0 falta de recursos, y que en la actualidad son los padres de familia quienes sostienen la instituci\u00f3n con sus aportaciones. En entrevista, Fernando Mendoza &hellip; <a href=\"https:\/\/conurbados.com\/portal\/a-punto-de-cerrar-prepa-de-axochiapan-por-falta-de-recursos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;A punto de cerrar prepa de Axochiapan por falta de recursos&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":2310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[11,4],"tags":[],"class_list":["post-2309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-principal","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/conurbados.com\/portal\/wp-content\/uploads\/2016\/04\/Fernando-Mendoza.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7a247-Bf","_links":{"self":[{"href":"https:\/\/conurbados.com\/portal\/wp-json\/wp\/v2\/posts\/2309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conurbados.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conurbados.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conurbados.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conurbados.com\/portal\/wp-json\/wp\/v2\/comments?post=2309"}],"version-history":[{"count":1,"href":"https:\/\/conurbados.com\/portal\/wp-json\/wp\/v2\/posts\/2309\/revisions"}],"predecessor-version":[{"id":2311,"href":"https:\/\/conurbados.com\/portal\/wp-json\/wp\/v2\/posts\/2309\/revisions\/2311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conurbados.com\/portal\/wp-json\/wp\/v2\/media\/2310"}],"wp:attachment":[{"href":"https:\/\/conurbados.com\/portal\/wp-json\/wp\/v2\/media?parent=2309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conurbados.com\/portal\/wp-json\/wp\/v2\/categories?post=2309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conurbados.com\/portal\/wp-json\/wp\/v2\/tags?post=2309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}